{"id":1337,"count":7,"description":"Equipo M\u00e9dico Vyaire de la m\u00e1s alta calidad a los mejores precios. Soma Technology es un l\u00edder en la venta de equipo m\u00e9dico!","link":"https:\/\/www.somatechnology.com\/spanish\/fabricante\/equipo-medico-vyaire\/","name":"Vyaire","slug":"equipo-medico-vyaire","taxonomy":"pwb-brand","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.somatechnology.com\/spanish\/wp-json\/wp\/v2\/pwb-brand\/1337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.somatechnology.com\/spanish\/wp-json\/wp\/v2\/pwb-brand"}],"about":[{"href":"https:\/\/www.somatechnology.com\/spanish\/wp-json\/wp\/v2\/taxonomies\/pwb-brand"}],"wp:post_type":[{"href":"https:\/\/www.somatechnology.com\/spanish\/wp-json\/wp\/v2\/product?pwb-brand=1337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}